{"id":8843,"date":"2021-11-17T00:10:15","date_gmt":"2021-11-16T23:10:15","guid":{"rendered":"https:\/\/khodamehri.com\/?p=8843"},"modified":"2023-12-28T23:07:46","modified_gmt":"2023-12-28T22:07:46","slug":"%d8%ae%d9%88%d8%b1%d8%af%d9%86-%d8%a2%d8%a8-%da%a9%d8%a7%d9%81%db%8c-%d8%af%d8%b1-%d8%b1%d9%88%d8%b2","status":"publish","type":"post","link":"https:\/\/khodamehri.com\/fa\/blog\/%d8%ae%d9%88%d8%b1%d8%af%d9%86-%d8%a2%d8%a8-%da%a9%d8%a7%d9%81%db%8c-%d8%af%d8%b1-%d8%b1%d9%88%d8%b2\/","title":{"rendered":"\u062e\u0648\u0627\u0635 8 \u0644\u06cc\u0648\u0627\u0646 \u0622\u0628 \u062f\u0631 \u0631\u0648\u0632\u061f &#8211; \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0647\u06cc\u067e\u0646\u0648\u062a\u06cc\u0632\u0645 \u0628\u0631\u0627\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u06cc\u0644 \u0628\u0647 \u0646\u0648\u0634\u06cc\u062f\u0646 \u0622\u0628 \u06a9\u0627\u0641\u06cc"},"content":{"rendered":"<p>\u0622\u06cc\u0627 \u0627\u063a\u0644\u0628 \u0627\u062d\u0633\u0627\u0633 \u062e\u0633\u062a\u06af\u06cc \u0645\u06cc \u06a9\u0646\u06cc\u062f\u061f \u0622\u06cc\u0627 \u0627\u0632 \u062e\u0634\u06a9\u06cc \u067e\u0648\u0633\u062a \u0648 \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u062e\u0644\u0642\u06cc \u0631\u0646\u062c \u0645\u06cc \u0628\u0631\u06cc\u062f\u061f<\/p>\n<h2><strong>\u06a9\u0645 \u0622\u0628\u06cc \u0645\u0632\u0645\u0646<\/strong><\/h2>\n<p>\u062c\u0627\u0644\u0628 \u0627\u0633\u062a \u0628\u062f\u0627\u0646\u06cc\u062f \u060c \u062d\u062f\u0648\u062f 80 \u062f\u0631\u0635\u062f \u0645\u0631\u062f\u0645\u060c \u062f\u0686\u0627\u0631 \u06a9\u0645 \u0622\u0628\u06cc \u0645\u0632\u0645\u0646 \u0647\u0633\u062a\u0646\u062f. \u0645\u0627 \u0645\u06cc \u062f\u0627\u0646\u06cc\u0645 \u06a9\u0647 \u0628\u0627\u06cc\u062f \u0645\u0642\u062f\u0627\u0631 \u0632\u06cc\u0627\u062f\u06cc \u0622\u0628 \u0628\u0646\u0648\u0634\u06cc\u0645\u060c \u0627\u0645\u0627 \u0627\u0646\u062c\u0627\u0645 \u0627\u06cc\u0646 \u06a9\u0627\u0631 \u0631\u0627 \u062f\u0631 \u0637\u0648\u0644 \u0631\u0648\u0632 \u0641\u0631\u0627\u0645\u0648\u0634 \u0645\u06cc \u06a9\u0646\u06cc\u0645. \u0634\u0627\u06cc\u062f \u0647\u0645 \u0622\u0628 \u0628\u0647 \u0627\u0646\u062f\u0627\u0632\u0647 \u0646\u0648\u0634\u0627\u0628\u0647 \u0648 \u0642\u0647\u0648\u0647 \u0628\u0631\u0627\u06cc\u0645\u0627\u0646 \u062c\u0630\u0627\u0628 \u0646\u06cc\u0633\u062a! \u062f\u0631 \u0647\u0631 \u0635\u0648\u0631\u062a \u062d\u062a\u0645\u0627 \u0645\u06cc \u062f\u0627\u0646\u06cc\u062f \u06a9\u0647 \u062f\u0631 \u0631\u0648\u0632 \u0628\u0627\u06cc\u062f \u062a\u0627 <strong>\u0647\u0634\u062a \u0644\u06cc\u0648\u0627\u0646 \u0622\u0628<\/strong> \u0628\u0646\u0648\u0634\u06cc\u062f\u060c \u0627\u0645\u0627 \u0645\u062a\u0627\u0633\u0641\u0627\u0646\u0647 \u06af\u0641\u062a\u0646\u0634 \u0631\u0627\u062d\u062a \u062a\u0631 \u0627\u0632 \u0627\u0646\u062c\u0627\u0645 \u062f\u0627\u062f\u0646\u0634 \u0627\u0633\u062a.<\/p>\n<h2><strong>\u062f\u0632\u062f \u0622\u0628!<\/strong><\/h2>\n<p>\u062f\u0648 \u0633\u0648\u0645 \u0648\u0632\u0646 \u0628\u062f\u0646 \u0647\u0645\u0647 \u0645\u0627 \u0627\u0646\u0633\u0627\u0646 \u0647\u0627\u060c \u0627\u0632 \u0622\u0628 \u062a\u0634\u06a9\u06cc\u0644 \u0634\u062f\u0647 \u0627\u0633\u062a. \u062f\u0631 \u0646\u0638\u0631 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f:<\/p>\n<ul>\n<li>\u062e\u0648\u0646 \u0627\u0646\u0633\u0627\u0646 \u062d\u062f\u0648\u062f 83 \u062f\u0631\u0635\u062f \u0622\u0628 \u0627\u0633\u062a.<\/li>\n<li>74 \u062f\u0631\u0635\u062f \u0627\u0632 \u0645\u063a\u0632 \u0645\u0627\u060c \u0622\u0628 \u0627\u0633\u062a.<\/li>\n<li>\u06f2\u06f2 \u062f\u0631\u0635\u062f \u0627\u0633\u062a\u062e\u0648\u0627\u0646 \u0645\u0627 \u0622\u0628 \u0627\u0633\u062a.<\/li>\n<\/ul>\n<p>\u067e\u0633 \u062c\u0627\u06cc \u062a\u0639\u062c\u0628 \u0646\u06cc\u0633\u062a \u06a9\u0647 \u0646\u0648\u0634\u06cc\u062f\u0646 \u0622\u0628 \u0632\u06cc\u0627\u062f \u0628\u0627\u0639\u062b \u0645\u06cc \u0634\u0648\u062f \u0628\u0627 \u062a\u0645\u0631\u06a9\u0632 \u0628\u06cc\u0634\u062a\u0631\u06cc \u0641\u06a9\u0631 \u06a9\u0646\u06cc\u0645. \u0622\u0628\u060c \u062a\u0631\u06a9\u06cc\u0628\u0627\u062a \u062e\u0648\u0646 \u0645\u0627 \u0631\u0627 \u0633\u0627\u0644\u0645 \u0646\u06af\u0647 \u0645\u06cc \u062f\u0627\u0631\u062f \u0648 &nbsp;<a href=\"https:\/\/khodamehri.com\/fa\/blog\/%d8%af%d8%b1%d9%85%d8%a7%d9%86-%d9%81%d8%b4%d8%a7%d8%b1-%d8%ae%d9%88%d9%86\/\">\u0641\u0634\u0627\u0631 \u062e\u0648\u0646<\/a> \u0645\u0627 \u0631\u0627 \u062f\u0631 \u062d\u062f \u0646\u0631\u0645\u0627\u0644 \u062d\u0641\u0638 \u0645\u06cc\u06a9\u0646\u062f. \u0628\u0647 \u0639\u0644\u0627\u0648\u0647 \u0628\u0627\u0639\u062b \u0645\u06cc \u0634\u0648\u062f \u0639\u0636\u0644\u0627\u062a \u0648 \u0627\u0633\u062a\u062e\u0648\u0627\u0646 \u0647\u0627\u06cc \u0645\u0627 \u0628\u0647\u062a\u0631 \u06a9\u0627\u0631 \u06a9\u0646\u0646\u062f. \u0628\u0627 \u0627\u06cc\u0646 \u062d\u0627\u0644\u060c \u0628\u0627\u06cc\u062f \u0628\u062f\u0627\u0646\u06cc\u062f \u06a9\u0645 \u0622\u0628\u06cc \u0645\u0632\u0645\u0646 \u0641\u0642\u0637 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0646\u0646\u0648\u0634\u06cc\u062f\u0646 \u0622\u0628 \u06a9\u0627\u0641\u06cc \u0646\u06cc\u0633\u062a\u060c \u0628\u0644\u06a9\u0647 \u0628\u0647 \u062e\u0627\u0637\u0631 \u0645\u0635\u0631\u0641 \u0632\u06cc\u0627\u062f \u0645\u0648\u0627\u062f\u06cc \u0627\u0633\u062a \u06a9\u0647 <strong>\u0622\u0628 \u0628\u062f\u0646 \u0645\u0627 \u0631\u0627 \u0645\u06cc \u062f\u0632\u062f\u0646\u062f<\/strong>!<\/p>\n<p>\u0642\u0647\u0648\u0647\u060c \u0686\u0627\u06cc\u060c \u0646\u0648\u0634\u0627\u0628\u0647\u200c\u0647\u0627\u06cc \u06af\u0627\u0632\u062f\u0627\u0631\u060c \u06a9\u0631\u0628\u0648\u0647\u06cc\u062f\u0631\u0627\u062a\u0647\u0627 \u0648 \u0627\u0644\u0628\u062a\u0647 \u0627\u0644\u06a9\u0644\u060c \u0647\u0645\u06af\u06cc \u0628\u0627 \u062a\u062d\u0631\u06cc\u06a9 \u0628\u062f\u0646 \u0645\u0627 \u0628\u0647 \u0627\u0632 \u062f\u0633\u062a \u062f\u0627\u062f\u0646 \u0622\u0628 \u0628\u06cc\u0634\u062a\u0631\u060c \u0627\u06cc\u0646 \u0645\u0627\u06cc\u0639 \u06af\u0631\u0627\u0646 \u0628\u0647\u0627 \u0631\u0627 \u0627\u0632 \u0645\u0627 <strong><u>\u0645\u06cc\u200c\u062f\u0632\u062f\u0646\u062f<\/u><\/strong>.<\/p>\n\n<div id=\"rank-math-faq\" class=\"rank-math-block\">\n<div class=\"rank-math-list \">\n<div id=\"faq-question-1637104310762\" class=\"rank-math-list-item\">\n<h2 class=\"rank-math-question \">\u0622\u0628 \u0686\u0647 \u0641\u0627\u06cc\u062f\u0647 \u0627\u06cc \u0628\u0631\u0627\u06cc \u0628\u062f\u0646 \u0645\u0627 \u062f\u0627\u0631\u062f\u061f<\/h2>\n<div class=\"rank-math-answer \">\n\n<p>\u2022 \u0622\u0628 \u0628\u0647 \u0647\u0636\u0645 \u063a\u0630\u0627\u060c \u062c\u0630\u0628 \u0648\u06cc\u062a\u0627\u0645\u06cc\u0646 \u0647\u0627 \u0648 \u0645\u0648\u0627\u062f \u0645\u0639\u062f\u0646\u06cc \u0636\u0631\u0648\u0631\u06cc \u06a9\u0645\u06a9 \u0645\u06cc \u06a9\u0646\u062f.<br \/>\u2022 \u0622\u0628 \u0628\u0631\u0627\u06cc \u0633\u0645 \u0632\u062f\u0627\u06cc\u06cc \u06a9\u0644\u06cc\u0647 \u0647\u0627 \u0648 \u06a9\u0628\u062f \u0636\u0631\u0648\u0631\u06cc \u0627\u0633\u062a \u0648 \u0628\u0647 \u062f\u0641\u0639 \u0645\u0648\u0627\u062f \u0632\u0627\u0626\u062f \u0628\u062f\u0646 \u06a9\u0645\u06a9 \u0645\u06cc \u06a9\u0646\u062f.<br \/>\u2022 \u0622\u0628 \u0639\u0645\u0644\u06a9\u0631\u062f \u0641\u06cc\u0632\u06cc\u06a9\u06cc \u0648 \u0630\u0647\u0646\u06cc \u0645\u0627 \u0631\u0627 \u0628\u0647\u0628\u0648\u062f \u0645\u06cc \u0628\u062e\u0634\u062f.<br \/>\u2022 \u0622\u0628 \u067e\u0648\u0633\u062a \u0645\u0627 \u0631\u0627 \u0635\u0627\u0641 \u0648 \u0634\u0641\u0627\u0641 \u0646\u06af\u0647 \u0645\u06cc \u062f\u0627\u0631\u062f \u0648 \u062f\u0631\u0648\u0627\u0642\u0639 \u06cc\u06a9 \u0632\u06cc\u0628\u0627 \u06a9\u0646\u0646\u062f\u0647 \u0637\u0628\u06cc\u0639\u06cc \u0627\u0633\u062a.<br \/>\u2022 \u0622\u0628 \u0628\u0647 \u06a9\u0627\u0647\u0634 \u0648\u0632\u0646 \u06a9\u0645\u06a9 \u0645\u06cc \u06a9\u0646\u062f \u0632\u06cc\u0631\u0627 \u06cc\u06a9 \u0633\u0631\u06a9\u0648\u0628 \u06a9\u0646\u0646\u062f\u0647 \u0637\u0628\u06cc\u0639\u06cc \u0627\u0634\u062a\u0647\u0627 \u0627\u0633\u062a.<br \/>\u2022 \u0646\u0648\u0634\u06cc\u062f\u0646 \u0622\u0628 \u0632\u06cc\u0627\u062f \u0628\u0631\u0627\u06cc \u0642\u0644\u0628 \u0639\u0627\u0644\u06cc \u0627\u0633\u062a.<br \/>\u2022 \u0648 \u0647\u0632\u0627\u0631 \u0646\u06a9\u062a\u0647 \u062f\u06cc\u06af\u0631 \u2026..<\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n<p>\u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0646\u06a9\u0627\u062a\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u062e\u0648\u0627\u0647\u0645 \u06af\u0641\u062a \u06a9\u0647 \u0628\u0627 \u0639\u0645\u0644 \u0628\u0647 \u0622\u0646 \u0647\u0627 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u062e\u0648\u062f \u0631\u0627 \u0627\u0632 \u062e\u0637\u0631 \u06a9\u0645 \u0622\u0628\u06cc \u0646\u062c\u0627\u062a \u062f\u0647\u06cc\u062f.<\/p>\n<p>&nbsp;\u0627\u0648\u0644\u0627\u064b \u0641\u0642\u0637 \u0648\u0642\u062a\u06cc \u062a\u0634\u0646\u0647 \u0647\u0633\u062a\u06cc\u062f \u0622\u0628 \u0646\u0646\u0648\u0634\u06cc\u062f\u061b \u0632\u06cc\u0631\u0627 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0648\u0627\u0642\u0639 \u0634\u0645\u0627 \u0645\u06cc \u062e\u0648\u0627\u0647\u06cc\u062f \u0628\u0631\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u06a9\u0645 \u0622\u0628\u06cc \u0622\u0628 \u0628\u0646\u0648\u0634\u06cc\u062f \u0648\u0644\u06cc \u0628\u0627\u06cc\u062f \u0628\u062f\u0627\u0646\u06cc\u062f \u0627\u06af\u0631 \u062a\u0634\u0646\u0647 \u0647\u0633\u062a\u06cc\u062f \u067e\u0633 \u06a9\u0645 \u0622\u0628\u06cc\u060c \u0627\u0632 \u0642\u0628\u0644 \u0628\u0631\u0627\u06cc \u0628\u062f\u0646\u062a\u0627\u0646 \u0627\u062a\u0641\u0627\u0642 \u0627\u0641\u062a\u0627\u062f\u0647 \u0627\u0633\u062a.<\/p>\n<p>\u0622\u0628 \u0631\u0627 \u0647\u0645\u06cc\u0634\u0647 \u0647\u0645\u0631\u0627\u0647 \u062e\u0648\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f. <strong><u>\u0627\u06af\u0631 \u06cc\u06a9 \u0628\u0637\u0631\u06cc \u0622\u0628 \u0647\u0645\u0631\u0627\u0647 \u062e\u0648\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f\u060c \u0628\u0647 \u0634\u0645\u0627 \u06cc\u0627\u062f\u0622\u0648\u0631\u06cc \u0645\u06cc \u06a9\u0646\u062f \u06a9\u0647 \u0627\u0632 \u0622\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.<\/u><\/strong> \u062d\u062a\u06cc \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u062f \u06cc\u06a9 \u062a\u0627\u06cc\u0645\u0631 \u0631\u0648\u06cc \u0631\u0627\u06cc\u0627\u0646\u0647 \u0634\u062e\u0635\u06cc \u06cc\u0627 \u062a\u0644\u0641\u0646 \u0647\u0645\u0631\u0627\u0647 \u062e\u0648\u062f \u062a\u0646\u0638\u06cc\u0645 \u06a9\u0646\u06cc\u062f \u062a\u0627 \u0628\u0647 \u0634\u0645\u0627 \u06cc\u0627\u062f\u0622\u0648\u0631\u06cc \u06a9\u0646\u062f \u06a9\u0647 \u0622\u0628 \u0628\u0646\u0648\u0634\u06cc\u062f. \u0627\u06cc\u0646 \u06a9\u0627\u0631 \u0631\u0627 \u062a\u0627 \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0647 \u0646\u0648\u0634\u06cc\u062f\u0646 \u0622\u0628 \u06a9\u0627\u0641\u06cc \u0639\u0627\u062f\u062a \u06a9\u0646\u06cc\u062f \u0627\u062f\u0627\u0645\u0647 \u062f\u0647\u06cc\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0628\u0647 \u06cc\u0627\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u06a9\u0647 \u0644\u0627\u0632\u0645 \u0646\u06cc\u0633\u062a \u06cc\u06a9\u0628\u0627\u0631\u0647 \u0645\u0642\u062f\u0627\u0631 \u0632\u06cc\u0627\u062f\u06cc \u0622\u0628 \u0628\u0646\u0648\u0634\u06cc\u062f. \u0628\u0627 \u0645\u0635\u0631\u0641 \u0645\u0646\u0638\u0645 \u0622\u0628\u060c \u062e\u0648\u062f \u0631\u0627 \u060c\u062f\u0631 \u0637\u0648\u0644 \u0631\u0648\u0632 \u062a\u0627\u0645\u06cc\u0646 \u06a9\u0646\u06cc\u062f.<\/p>\n<h2><strong>\u0686\u0637\u0648\u0631 \u0645\u06cc \u062a\u0648\u0627\u0646\u06cc\u0645 \u0628\u0627 \u0647\u06cc\u067e\u0646\u0648\u062a\u06cc\u0632\u0645 \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u0646\u0648\u0634\u06cc\u062f\u0646 \u0622\u0628 \u0639\u0627\u062f\u062a \u062f\u0647\u06cc\u0645\u061f<\/strong><\/h2>\n<p>\u0639\u0627\u062f\u062a \u0647\u0627\u06cc \u0645\u0627 \u062a\u0648\u0633\u0637 \u0636\u0645\u06cc\u0631 \u0646\u0627\u062e\u0648\u062f\u0622\u06af\u0627\u0647 \u0645\u0627 \u06a9\u0646\u062a\u0631\u0644 \u0645\u06cc \u0634\u0648\u0646\u062f. \u0628\u0647 \u0647\u0645\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u0627\u0633\u062a \u06a9\u0647 \u062a\u0631\u06a9 \u0639\u0627\u062f\u062a \u0647\u0627\u06cc \u0628\u062f \u0628\u0633\u06cc\u0627\u0631 \u0633\u062e\u062a \u0627\u0633\u062a!<\/p>\n<p><a href=\"https:\/\/khodamehri.com\/fa\/blog\/%d9%87%db%8c%d9%be%d9%86%d9%88%d8%aa%db%8c%d8%b2%d9%85-%da%86%db%8c%d8%b3%d8%aa\/\">\u0647\u06cc\u067e\u0646\u0648\u062a\u06cc\u0632\u0645<\/a> \u0628\u0627 \u0627\u06cc\u062c\u0627\u062f \u0639\u0627\u062f\u062a\u06cc \u062f\u0631 \u0630\u0647\u0646 \u0646\u0627\u062e\u0648\u062f\u0622\u06af\u0627\u0647 \u0634\u0645\u0627\u060c \u06a9\u0645\u06a9 \u0645\u06cc \u06a9\u0646\u062f \u062a\u0627 \u0627\u062d\u0633\u0627\u0633 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0645\u06cc\u0644 \u0628\u0647 \u0646\u0648\u0634\u06cc\u062f\u0646 \u0622\u0628 \u062f\u0627\u0631\u06cc\u062f \u0648 \u0627\u0646\u06af\u06cc\u0632\u0647 \u0634\u0645\u0627 \u0631\u0627 \u062d\u0641\u0638 \u0645\u06cc \u06a9\u0646\u062f \u062a\u0627 \u0628\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0647 \u0633\u0631\u0639\u062a \u0627\u0632 \u062a\u0645\u0627\u0645 \u0645\u0632\u0627\u06cc\u0627\u06cc \u0622\u0646 \u0628\u0647\u0631\u0647 \u0645\u0646\u062f \u0634\u0648\u06cc\u062f \u0648 \u0622\u0628 \u0641\u0631\u0627\u0648\u0627\u0646 \u0628\u0646\u0648\u0634\u06cc\u062f \u0648 \u0641\u0648\u0631\u0627\u064b \u0627\u062d\u0633\u0627\u0633 \u0628\u0647\u062a\u0631\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f.<\/p>\n<p>\u06cc\u0627\u0641\u062a\u0647 \u0647\u0627\u06cc \u06cc\u06a9 \u0645\u0637\u0627\u0644\u0639\u0647 \u0634\u0634 \u0633\u0627\u0644\u0647 \u0628\u0631 \u0631\u0648\u06cc \u0628\u06cc\u0634 \u0627\u0632 20000 \u0645\u0631\u062f \u0648 \u0632\u0646 \u0633\u0627\u0644\u0645 38 \u062a\u0627 100 \u0633\u0627\u0644\u0647 \u062f\u0631 \u0645\u062c\u0644\u0647 \u0622\u0645\u0631\u06cc\u06a9\u0627\u06cc\u06cc \u0627\u067e\u06cc\u062f\u0645\u06cc\u0648\u0644\u0648\u0698\u06cc (1 \u0645\u06cc 2002) \u0646\u0634\u0627\u0646 \u062f\u0627\u062f \u06a9\u0647 \u0632\u0646\u0627\u0646\u06cc \u06a9\u0647 \u0628\u06cc\u0634 \u0627\u0632 \u067e\u0646\u062c \u0644\u06cc\u0648\u0627\u0646 \u0622\u0628 \u062f\u0631 \u0631\u0648\u0632 \u0645\u06cc \u0646\u0648\u0634\u0646\u062f\u060c 41 \u062f\u0631\u0635\u062f \u06a9\u0645\u062a\u0631 \u062f\u0631 \u0645\u0639\u0631\u0636 \u062e\u0637\u0631 \u062d\u0645\u0644\u0647 \u0642\u0644\u0628\u06cc \u0642\u0631\u0627\u0631 \u062f\u0627\u0631\u0646\u062f \u0648 \u0646\u06a9\u062a\u0647 \u062c\u0627\u0644\u0628 \u062a\u0631 \u0627\u06cc\u0646 \u06a9\u0647 \u060c\u0627\u062b\u0631 \u0645\u062d\u0627\u0641\u0638\u062a\u06cc \u0622\u0628 \u062f\u0631 \u0645\u0631\u062f\u0627\u0646 \u062d\u062a\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0628\u0648\u062f.<\/p>\n<h2><strong>\u062e\u0648\u062f \u0647\u06cc\u067e\u0646\u0648\u062a\u06cc\u0632\u0645 \u0622\u0628 \u062e\u0648\u0631\u062f\u0646 \u06a9\u0627\u0641\u06cc \u062f\u0631 \u0637\u0648\u0644 \u0631\u0648\u0632<\/strong><\/h2>\n<p>\u062f\u0631\u0633\u062a \u0627\u0633\u062a \u06a9\u0647 \u0628\u0627 \u06cc\u06a9 \u062c\u0644\u0633\u0647 \u0647\u06cc\u067e\u0646\u0648\u062a\u0631\u0627\u067e\u06cc \u0645\u06cc\u062a\u0648\u0627\u0646\u06cc\u0645 \u0630\u0647\u0646 \u0646\u0627\u062e\u0648\u062f\u0622\u06af\u0627\u0647 \u0634\u0645\u0627 \u0631\u0627 \u0628\u0647 \u062e\u0648\u0631\u062f\u0646 \u0622\u0628 \u0628\u06cc\u0634\u062a\u0631 \u062f\u0631 \u0631\u0648\u0632 \u062a\u062d\u0631\u06cc\u06a9 \u06a9\u0646\u06cc\u0645 \u0648 \u0627\u062d\u0633\u0627\u0633 \u062a\u0634\u0646\u06af\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0628\u0648\u062c\u0648\u062f \u0628\u06cc\u0627\u0648\u0631\u06cc\u0645. \u0648\u0644\u06cc \u0628\u0631\u0627\u06cc \u0627\u06cc\u0646\u06a9\u0647 \u0628\u0631\u0627\u06cc \u0647\u0645\u06af\u0627\u0646 \u0627\u06cc\u0646 \u0645\u0633\u0626\u0644\u0647 \u06a9\u0647 \u0628\u062a\u0648\u0627\u0646\u0646\u062f \u06cc\u06a9 \u0647\u06cc\u067e\u0646\u0648\u062a\u0631\u0627\u067e \u067e\u06cc\u062f\u0627 \u06a9\u0646\u0646\u062f \u0645\u06cc\u0633\u0631 \u0646\u0645\u06cc\u0628\u0627\u0634\u062f \u0628\u0631\u0627\u06cc \u0647\u0645\u06cc\u0646 \u0645\u0646 \u06cc\u06a9 \u0641\u0627\u06cc\u0644 \u062e\u0648\u062f \u0647\u06cc\u067e\u0646\u0648\u062a\u06cc\u0632\u0645\u06cc \u062f\u0631 \u0622\u06cc\u0646\u062f\u0647 \u0628\u0647 \u0647\u0645\u06cc\u0646 \u0645\u0646\u0638\u0648\u0631 \u0645\u06cc\u062e\u0648\u0627\u0647\u0645 \u0637\u0631\u0627\u062d\u06cc \u06a9\u0646\u0645 \u06a9\u0647 \u062f\u0631 <a href=\"https:\/\/khodamehri.com\/fa\/product-category\/\u0641\u0627\u06cc\u0644-\u0647\u0627\u06cc-\u062e\u0648\u062f\u0647\u06cc\u067e\u0646\u0648\u062a\u06cc\u0632\u0645\u06cc\/\">\u0628\u062e\u0634 \u0641\u0627\u06cc\u0644 \u0647\u0627\u06cc \u062e\u0648\u062f \u0647\u06cc\u067e\u0646\u0648\u062a\u06cc\u0632\u0645\u06cc<\/a> \u0633\u0627\u06cc\u062a \u062f\u0631 \u0627\u062e\u062a\u06cc\u0627\u0631 \u0634\u0645\u0627 \u0642\u0631\u0627\u0631 \u062e\u0648\u0627\u0647\u0645 \u062f\u0627\u062f.<\/p>\n<p>\u0645\u0637\u0645\u0626\u0646 \u0647\u0633\u062a\u0645 \u06a9\u0647 \u0627\u06cc\u0646 \u0641\u0627\u06cc\u0644 \u062e\u0648\u062f \u0647\u06cc\u067e\u0646\u0648\u062a\u06cc\u0632\u0645\u06cc \u0645\u06cc\u062a\u0648\u0627\u0646\u062f \u0634\u0645\u0627 \u0631\u0627 \u0627\u0632 \u062a\u0646\u0628\u0644\u06cc \u0648 \u06cc\u0627 \u0641\u0631\u0627\u0645\u0648\u0634\u06cc \u062f\u0648\u0631 \u06a9\u0646\u062f \u0648 \u0628\u062f\u0646 \u06a9\u0645 \u0622\u0628\u062a\u0627\u0646 \u0631\u0627 \u062f\u0648\u0628\u0627\u0631\u0647 \u0633\u06cc\u0631\u0627\u0628 \u06a9\u0646\u062f.<\/p>\n<p><\/p>\n\n\n<style>.h_iframe-aparat_embed_frame{position:relative;}.h_iframe-aparat_embed_frame .ratio{display:block;width:100%;height:auto;}.h_iframe-aparat_embed_frame iframe{position:absolute;top:0;left:0;width:100%;height:100%;}<\/style><div class=\"h_iframe-aparat_embed_frame\"><span style=\"display: block;padding-top: 57%\"><\/span><iframe src=\"https:\/\/www.aparat.com\/video\/video\/embed\/videohash\/39riH\/vt\/frame\" allowfullscreen=\"true\" webkitallowfullscreen=\"true\" mozallowfullscreen=\"true\"><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0622\u06cc\u0627 \u0627\u063a\u0644\u0628 \u0627\u062d\u0633\u0627\u0633 \u062e\u0633\u062a\u06af\u06cc \u0645\u06cc \u06a9\u0646\u06cc\u062f\u061f \u0622\u06cc\u0627 \u0627\u0632 \u062e\u0634\u06a9\u06cc \u067e\u0648\u0633\u062a \u0648 \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u062e\u0644\u0642\u06cc \u0631\u0646\u062c \u0645\u06cc \u0628\u0631\u06cc\u062f\u061f \u06a9\u0645 \u0622\u0628\u06cc \u0645\u0632\u0645\u0646 \u062c\u0627\u0644\u0628 \u0627\u0633\u062a \u0628\u062f\u0627\u0646\u06cc\u062f \u060c \u062d\u062f\u0648\u062f 80 \u062f\u0631\u0635\u062f \u0645\u0631\u062f\u0645\u060c \u062f\u0686\u0627\u0631 \u06a9\u0645 \u0622\u0628\u06cc \u0645\u0632\u0645\u0646 \u0647\u0633\u062a\u0646\u062f. \u0645\u0627 \u0645\u06cc \u062f\u0627\u0646\u06cc\u0645 \u06a9\u0647 \u0628\u0627\u06cc\u062f \u0645\u0642\u062f\u0627\u0631 \u0632\u06cc\u0627\u062f\u06cc \u0622\u0628 \u0628\u0646\u0648\u0634\u06cc\u0645\u060c \u0627\u0645\u0627 \u0627\u0646\u062c\u0627\u0645 \u0627\u06cc\u0646 \u06a9\u0627\u0631 \u0631\u0627 \u062f\u0631 \u0637\u0648\u0644 \u0631\u0648\u0632 \u0641\u0631\u0627\u0645\u0648\u0634 \u0645\u06cc \u06a9\u0646\u06cc\u0645. \u0634\u0627\u06cc\u062f \u0647\u0645 \u0622\u0628&#8230;<\/p>\n","protected":false},"author":1,"featured_media":8856,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[16],"tags":[],"class_list":["post-8843","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-16"],"_links":{"self":[{"href":"https:\/\/khodamehri.com\/fa\/wp-json\/wp\/v2\/posts\/8843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/khodamehri.com\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/khodamehri.com\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/khodamehri.com\/fa\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/khodamehri.com\/fa\/wp-json\/wp\/v2\/comments?post=8843"}],"version-history":[{"count":0,"href":"https:\/\/khodamehri.com\/fa\/wp-json\/wp\/v2\/posts\/8843\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/khodamehri.com\/fa\/wp-json\/wp\/v2\/media\/8856"}],"wp:attachment":[{"href":"https:\/\/khodamehri.com\/fa\/wp-json\/wp\/v2\/media?parent=8843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/khodamehri.com\/fa\/wp-json\/wp\/v2\/categories?post=8843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/khodamehri.com\/fa\/wp-json\/wp\/v2\/tags?post=8843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}